{"id":413450,"date":"2026-05-13T05:47:57","date_gmt":"2026-05-13T08:47:57","guid":{"rendered":"https:\/\/midassorte.com.br\/resultado\/?p=413450"},"modified":"2026-05-13T05:47:57","modified_gmt":"2026-05-13T08:47:57","slug":"sorteio-da-federal-quarta-13-05","status":"publish","type":"post","link":"https:\/\/midassorte.com.br\/resultado\/sorteio-da-federal-quarta-13-05\/","title":{"rendered":"Resultado Sorteio da Federal  &#8211; Quarta &#8211; 13\/05 &#8211; Informa\u00e7\u00e3o"},"content":{"rendered":"<p>Resultado Sorteio da Federal de hoje, veja aqui! Acompanhamos os Sorteios e divulgamos.<\/p>\n<p>Confira o resultado <span class=\"fd\">sorteio da federal dessa Quarta-feira, 13\/05\/2026<\/span>. Loteria Federal 6065, sorteado <span class=\"ms\">a partir das 20:00h (hor\u00e1rio de Bras\u00edlia)<\/span>.. As extra\u00e7\u00f5es da Loteria Federal s\u00e3o realizadas sob a supervis\u00e3o e responsabilidade da Caixa Econ\u00f4mica Federal.<\/p>\n<hr>\n<p>PUBLICIDADE<br \/>\n<ins class=\"adsbygoogle\"\n     style=\"display:block;min-height:100px\"\n     data-ad-client=\"ca-pub-2731125202615360\"\n     data-ad-slot=\"1764357550\"\n     data-ad-format=\"auto\"\n     data-full-width-responsive=\"true\"><\/ins><\/p>\n<div class=\"div-painel\">\n<h2>Resultado Sorteio da Federal 6065 <\/h2>\n<p> <em> &#8211; (informa\u00e7\u00e3o MidasSorte)<\/em><br \/>\n<span class=\"ms\">&#8230;&#8230;. sorteado a partir das <strong>20:00h (hor\u00e1rio de Bras\u00edlia)<\/span>, <\/p>\n<div class=\"paineldezenas\">\n<table border=\"0\" class=\"federal-premios\">\n<tbody>\n<tr><td><strong>1\u00ba PR\u00caMIO<\/strong><\/td><td><span id=\"fd\">.....<\/span><\/td><td>R$ ............<\/td><\/tr>\n<tr><td><strong>2\u00ba PR\u00caMIO<\/strong><\/td><td><span id=\"fd\">.....<\/span><\/td><td>R$ ............<\/td><\/tr>\n<tr><td><strong>3\u00ba PR\u00caMIO<\/strong><\/td><td><span id=\"fd\">.....<\/span><\/td><td>R$ ............<\/td><\/tr>\n<tr><td><strong>4\u00ba PR\u00caMIO<\/strong><\/td><td><span id=\"fd\">.....<\/span><\/td><td>R$ ............<\/td><\/tr>\n<tr><td><strong>5\u00ba PR\u00caMIO<\/strong><\/td><td><span id=\"fd\">.....<\/span><\/td><td>R$ ............<\/td><\/tr>\n<\/tbody><\/table>\n\n<\/div>\n<p><strong>S\u00e9rie \u00fanica (A )  &#8211; 92.000 bilhetes<\/strong>. <\/p>\n<strong>Os Bilhetes ganhadores dos pr\u00eamios do Resultado da Federal 6065 foram distribu\u00eddos para:<\/strong><br>\n1\u00ba Pr\u00eamio: <span class=\"fd\">***<\/span><br>\n2\u00ba Pr\u00eamio: <span class=\"fd\">***<\/span><br>\n3\u00ba Pr\u00eamio: <span class=\"fd\">***<\/span><br>\n4\u00ba Pr\u00eamio: <span class=\"fd\">***<\/span><br>\n5\u00ba Pr\u00eamio: <span class=\"fd\">***<\/span><br>\n\n<\/div>\n<p>PUBLICIDADE<br \/>\n<ins class=\"adsbygoogle\"\n     style=\"display:block;min-height:100px\"\n     data-ad-client=\"ca-pub-2731125202615360\"\n     data-ad-slot=\"5848493679\"\n     data-ad-format=\"auto\"\n     data-full-width-responsive=\"true\"><\/ins><\/p>\n<hr \/>\n<p><a href=\"https:\/\/midassorte.com.br\/resultado\/sorteio-da-federal-sabado-09-05\/\"<strong>Clique\/confira SORTEIO ANTERIOR &#8211; as milhares sorteadas e as premia\u00e7\u00f5es distribu\u00eddas.<\/strong><\/a><\/p>\n<hr \/>\n<p>Conhe\u00e7a sempre em primeira m\u00e3o o <span class=\"fd\">resultado sorteio da federal do dia<\/span>, que \u00e9 postado aqui no MidasSorte assim que ocorrem os sorteios, pr\u00eamio a pr\u00eamio. E, se poss\u00edvel, passe em uma casa lot\u00e9rica, adquira seu bilhete, ponha F\u00e9 e confira aqui o Resultado da Federal 6065.<br \/>\nResultado Sorteio da Federal, a Loteria de Bilhetes!<\/p>\n<hr \/>\n<p>Fra\u00e7\u00e3o; dessa Extra\u00e7\u00e3o 6065 de Quarta-feira, adquirida pelo Site, contendo o Palpite Oficial do Site, competindo com os Palpites enviados pelas Pessoas:<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-05-37-38-300x225.jpg\" alt=\"resultado sorteio da Federal de hoje\" width=\"300\" height=\"225\" class=\"alignnone size-medium wp-image-413451\" srcset=\"https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-05-37-38-300x225.jpg 300w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-05-37-38-1024x768.jpg 1024w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-05-37-38-768x576.jpg 768w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-05-37-38-640x480.jpg 640w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-05-37-38-720x540.jpg 720w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-05-37-38.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<hr \/>\n<hr \/>\n<p>==== <a href=\"https:\/\/midassorte.com.br\/resultado\/category\/voce-e-bom-de-palpite-participe-aqui\/\"><strong>P\u00c1GINAS ESPEC\u00cdFICAS PARA PALPITES &#8211; ACESSE AQUI E DIVIRTA-SE<\/strong><\/a><\/p>\n<hr \/>\n<h2>Esclarecimentos sobre o Resultado Sorteio da Federal 6065<\/h2>\n<p>A Loteria Federal \u00e9 a mais tradicional do Brasil. Com a Loteria Federal, voc\u00ea, al\u00e9m das chances de acertar um dos cinco pr\u00eamios principais, tamb\u00e9m pode ganhar, se acertar:<\/p>\n<p>\u2022 N\u00fameros que sejam as aproxima\u00e7\u00f5es imediatamente Anterior e Posterior ao N\u00famero sorteado no 1\u00ba Pr\u00eamio.<br \/>\n\u2022\u2022 A Milhar, a Centena, e a Dezena de qualquer um dos n\u00fameros sorteados nos cinco pr\u00eamios principais.<br \/>\n\u2022\u2022\u2022 Bilhetes cujos n\u00fameros contenham a Dezena final id\u00eantica a umas das 3 (tr\u00eas) dezenas anteriores ou das 3 (tr\u00eas) dezenas posteriores \u00e0 Dezena do n\u00famero sorteado para o 1\u00ba pr\u00eamio, excetuando-se os premiados pela aproxima\u00e7\u00e3o anterior e posterior.<br \/>\n\u2022\u2022\u2022\u2022 A Unidade do primeiro pr\u00eamio.<\/p>\n<p>TOTAL DE BILHETES EMITIDOS EM UMA EXTRA\u00c7\u00c3O DA LOTERIA FEDERAL:( <em>A partir de Mar\u00e7o\/25 <\/em>)<br \/>\n<span class=\"ds\">====. QUARTA-FEIRA &#8211; 92.000 BILHETES.<br \/>\n====  S\u00c1BADO &#8211;       96.000 BILHETES.<br \/>\n=== MILION\u00c1RIA MENSAL &#8211;  84.000 BILHETES.<br \/>\n==== ESPECIAL DE NATAL &#8211; 85.000 BILHETES ( por s\u00e9rie)<\/span><\/p>\n<p>Os sorteios das extra\u00e7\u00f5es s\u00e3o realizados nas quartas e s\u00e1bados com pr\u00eamios principais de R$ 500 mil nas Quartas e nos S\u00e1bados. Uma vez por M\u00eas, h\u00e1 a Extra\u00e7\u00e3o Milion\u00e1ria Federal, com Pr\u00eamio de R$ 1.350.000,00. A pr\u00f3xima extra\u00e7\u00e3o, A <strong>Extra\u00e7\u00e3o 6066<\/strong> &#8211; 16\/05\/26 &#8211; <strong>Ser\u00e1 a Extra\u00e7\u00e3o Milion\u00e1ria Especial do M\u00eas de MAIO 2026<\/strong>.<\/p>\n<hr \/>\n<h2>Como participar do Resultado Sorteio da Federal 6065: <\/h2>\n<p>O bilhete pode ser adquirido inteiro ou em fra\u00e7\u00e3o &#8211; cada bilhete possui 10 fra\u00e7\u00f5es e a premia\u00e7\u00e3o \u00e9 proporcional ao n\u00famero de fra\u00e7\u00f5es que voc\u00ea adquire.<br \/>\nOs Bilhetes, desse Resultado sorteio da Federal 6065, est\u00e3o dispon\u00edveis para venda nas Casas Lot\u00e9ricas. Cada fra\u00e7\u00e3o ao pre\u00e7o de R$ 4,00.<br \/>\nA Loteria Federal \u00e9 uma modalidade de loteria administrada pela <a href=\"http:\/\/www.caixa.gov.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Caixa Econ\u00f4mica Federal<\/a>.<\/p>\n<hr \/>\n<p><strong>Curiosidade:<\/strong> As pessoas compram os bilhetes atribuindo-lhes uma rela\u00e7\u00e3o com eventos de Sonhos e Bichos. Essa tradicional rela\u00e7\u00e3o Bichos\/N\u00fameros foi criada em 1892 pelo Bar\u00e3o de Drumond, para angariar fundos para sustentar o 1\u00ba zool\u00f3gico do Rio de Janeiro e adaptada para os dias de hoje.<\/p>\n<hr \/>\n<p><strong><span class=\"fd\">Aten\u00e7\u00e3o: Em nosso site, <a href=\"http:\/\/midassorte.com.br\/resultado\/\" target=\"_blank\" rel=\"noopener noreferrer\">midassorte.com.br<\/a> ,<br \/>\nN\u00e3o temos promo\u00e7\u00f5es por telefone\/mensagens e n\u00e3o fazemos qualquer contatos de venda e promo\u00e7\u00e3o por telefone.<br \/>\n<strong>N\u00c3O VENDEMOS JOGOS\/APOSTAS<\/strong>.<br \/>\nNosso trabalho consiste em divulga\u00e7\u00e3o de resultados e palpites de Loterias, atrav\u00e9s do Site.<\/span><\/strong><\/p>\n<p><strong>Nossos \u00daNICOS canais de comunica\u00e7\u00e3o s\u00e3o:<br \/>\n\u2022\u2022\u2022 <strong>E-MAIL<\/strong>: midasgarante@gmail.com<br \/>\n\u2022\u2022\u2022 <strong>WHATSAPP<\/strong>: MidasSorte: 55 31 97524 8524.<\/strong><\/p>\n<p><span class=\"fd\">&#8220;Midassorte \u00e9 Resultado e resultado \u00e9 Midassorte!!!<\/span><\/p>\n<p><span class=\"fd\">Informa\u00e7\u00e3o Importante para Participante em Jogo Cortesia MidasSorte:<\/span><br \/>\n1- QUANDO PARTICIPANTE em Jogos Cortesia MidasSorte, a Pessoa receber\u00e1, em seu E-mail\/Whats, a C\u00f3pia de registro do Jogo &#8211;<br \/>\n\u2022<strong>&#8220;Se n\u00e3o lhe enviamos essa mensagem em seu E-mail\/WhatsApp, voc\u00ea n\u00e3o est\u00e1 participando&#8221;.<\/strong><\/span>..<br \/>\n\u2022\u2022\u2022<br \/>\nBoa sorte, nessa Extra\u00e7\u00e3o <strong>Resultado Sorteio da Federal 6065.<\/strong><br \/>\nMidasSorte&#8230;dia a dia, loteria a loteria! Boa Sorte!!!<br \/>\nEditor Respons\u00e1vel: <em>Jos\u00e9 Raimundo Vieira<\/em>.<\/p>\n<p>\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultado Sorteio da Federal de hoje, veja aqui! Acompanhamos os Sorteios e divulgamos. Confira o resultado sorteio da federal dessa Quarta-feira, 13\/05\/2026. Loteria Federal 6065, sorteado a partir das 20:00h (hor\u00e1rio de Bras\u00edlia).. As extra\u00e7\u00f5es da Loteria Federal s\u00e3o realizadas &hellip; <a href=\"https:\/\/midassorte.com.br\/resultado\/sorteio-da-federal-quarta-13-05\/\">Continuar lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[651],"tags":[],"class_list":["post-413450","post","type-post","status-publish","format-standard","hentry","category-loteria-federal"],"_links":{"self":[{"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/posts\/413450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/comments?post=413450"}],"version-history":[{"count":1,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/posts\/413450\/revisions"}],"predecessor-version":[{"id":413452,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/posts\/413450\/revisions\/413452"}],"wp:attachment":[{"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/media?parent=413450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/categories?post=413450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/tags?post=413450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}