{"id":370785,"date":"2025-02-08T21:15:43","date_gmt":"2025-02-09T00:15:43","guid":{"rendered":"https:\/\/midassorte.com.br\/resultado\/?p=370785"},"modified":"2025-02-10T07:59:02","modified_gmt":"2025-02-10T10:59:02","slug":"resultado-lotofacil-3315-sabado-08-02-informacao","status":"publish","type":"post","link":"https:\/\/midassorte.com.br\/resultado\/resultado-lotofacil-3315-sabado-08-02-informacao\/","title":{"rendered":"Resultado Lotof\u00e1cil 3315 &#8211; S\u00e1bado &#8211; 08\/02 &#8211; Informa\u00e7\u00e3o"},"content":{"rendered":"<p>\u2022\u2022\u2022<br \/>\n<span class=\"ms\">ESTAMOS AQUI!..h\u00e1 11 anos&#8230;  &#8220;Dia a dia&#8230;.Loteria a loteria&#8230;Resultados e Palpites de Loterias!!!<\/span><br \/>\n<strong>N\u00c3O VENDEMOS JOGOS\/APOSTAS<\/strong> &#8211;<\/p>\n<p><strong>ATEN\u00c7\u00c3O<\/strong>:<br \/>\n  <span class=\"lf\">MIDASSORTE => N\u00c3O SOMOS, N\u00c3O TEMOS PLATAFORMA DE APOSTAS!!!<\/span>&#8230; (<strong><em>cuidado com imita\u00e7\u00f5es<\/em><\/strong>)<\/p>\n<hr>\n<p>\u2022\u2022\u2022<\/p>\n<p>Confira o resultado da <strong>Lotof\u00e1cil 3315<\/strong>, hoje, nesse S\u00e1bado, <strong>08\/02\/2025, a partir das 20:00h (hor\u00e1rio de Bras\u00edlia)<\/strong>, no &#8220;Espa\u00e7o da Sorte de Loterias da Caixa&#8221; na Av. Paulista, 750, S\u00e3o Paulo\/SP.<br \/>\nO MidasSorte acompanha o sorteio da <strong>Lotof\u00e1cil 3315<\/strong>, dezena a dezena. Curta com a gente toda a emo\u00e7\u00e3o da Lotof\u00e1cil de hoje. O sorteio \u00e9 realizado sob a supervis\u00e3o e responsabilidade da Caixa Econ\u00f4mica Federal<\/p>\n<p><strong>Publicidade<\/strong><br \/>\n<ins class=\"adsbygoogle\"\n     style=\"display:block;min-height:100px\"\n     data-ad-client=\"ca-pub-2731125202615360\"\n     data-ad-slot=\"5848493679\"\n     data-ad-format=\"auto\"\n     data-full-width-responsive=\"true\"><\/ins><\/p>\n<div class=\"div-painel\">\n<h2>Resultado Lotof\u00e1cil 3315<\/h2>\n<p>  &#8211;  &#8230;<br \/>\n&#8230;.<strong> <em>informa\u00e7\u00e3o MidasSorte<\/em><\/strong>.<\/p>\n<p>DEZENAS EM ORDEM DE SORTEIO<\/p>\n<div class=\"paineldezenas\">\n<span id=\"lf\">06<\/span><span id=\"lf\">08<\/span><span id=\"lf\">21<\/span><span id=\"lf\">17<\/span><span id=\"lf\">04<\/span><br \/>\n<span id=\"lf\">07<\/span><span id=\"lf\">25<\/span><span id=\"lf\">14<\/span><span id=\"lf\">24<\/span><span id=\"lf\">18<\/span><br \/>\n<span id=\"lf\">03<\/span><span id=\"lf\">02<\/span><span id=\"lf\">11<\/span><span id=\"lf\">09<\/span><span id=\"lf\">12<\/span>\n<\/div>\n<h2>Resultado Lotof\u00e1cil 3315<\/h2>\n<p>DEZENAS EM ORDEM CRESCENTE<\/p>\n<div class=\"paineldezenas\">\n<span id=\"lf\">02<\/span><span id=\"lf\">03<\/span><span id=\"lf\">04<\/span><span id=\"lf\">06<\/span><span id=\"lf\">07<\/span><br \/>\n<span id=\"lf\">08<\/span><span id=\"lf\">09<\/span><span id=\"lf\">11<\/span><span id=\"lf\">12<\/span><span id=\"lf\">14<\/span><br \/>\n<span id=\"lf\">17<\/span><span id=\"lf\">18<\/span><span id=\"lf\">21<\/span><span id=\"lf\">24<\/span><span id=\"lf\">25<\/span>\n<\/div>\n<h3>03 GANHADORES!<\/h3>\n<p>\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022<br \/>\n<span class=\"lm\">Pr\u00eamio Estimado do Resultado Lotof\u00e1cil 3316<\/span>&#8230;. <\/p>\n<p><strong>SEGUNDA &#8211; 10\/02\/2025 &#8211;<br \/>\nR$ 1.700.000,00<\/strong><\/p>\n<p>Valor acumulado para a Lotof\u00e1cil da Independ\u00eancia 2025: R$ 56.981.954,00.<br \/>\nValor acumulado para proximo Concurso- &#8220;final zero&#8221;-3320: R$ 1.867.587,57.<\/p>\n<p>Publicidade<br \/>\n<ins class=\"adsbygoogle\"\n     style=\"display:block;min-height:100px\"\n     data-ad-client=\"ca-pub-2731125202615360\"\n     data-ad-slot=\"1764357550\"\n     data-ad-format=\"auto\"\n     data-full-width-responsive=\"true\"><\/ins><\/p>\n<h2>Premia\u00e7\u00e3o do Resultado Lotof\u00e1cil 3315<\/h2>\n<p><em>lan\u00e7amento feito t\u00e3o logo a Caixa a divulgue oficialmente!!!<\/em><\/p>\n<table border=\"0\">\n<thead>\n<tr>\n<td>Faixa de premia\u00e7\u00e3o<\/td>\n<td>N\u00ba de Ganhadores<\/td>\n<td>Valor de pr\u00eamio<\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>15 pontos<\/td>\n<td>03<\/td>\n<td><strong>R$ 1.564.958,77<\/strong><\/td>\n<\/tr>\n<tr>\n<td>14 pontos<\/td>\n<td>450<\/td>\n<td><strong>R$ 2.048,16<\/strong><\/td>\n<\/tr>\n<tr>\n<td>13 pontos<\/td>\n<td>15944<\/td>\n<td><strong>R$ 30,00<\/strong><\/td>\n<\/tr>\n<tr>\n<td>12 pontos<\/td>\n<td>188084<\/td>\n<td><strong>R$ 12,00<\/strong><\/td>\n<\/tr>\n<tr>\n<td>11 pontos<\/td>\n<td>1026607<\/td>\n<td><strong>R$ 6,00<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Cidades(s)<\/strong> em que foi(ram) feita(s) a(s) aposta(s) vencedora(s) do Resultado Lotof\u00e1cil 3315:<br \/>\n<strong>FORTALEZA\/CE; ITURAMA\/MG; NOSSA SENHORA DA GLORIA\/SE<\/strong>.<\/p>\n<div class=\"box-azul\"><a href=\"http:\/\/midassorte.com.br\/resultado\/category\/lotofacil-3\/\">Confira o resultado dos sorteios anteriores da Lotof\u00e1cil &#8211; dezenas sorteadas e premia\u00e7\u00f5es distribu\u00eddas.<\/a><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/01\/7cdfa9d8-149e-4cf7-88b3-6b53bcf09957-294x300.jpg\" alt=\"Resultado Lotof\u00e1cil 3315\" width=\"294\" height=\"300\" class=\"alignnone size-medium wp-image-369942\" srcset=\"https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/01\/7cdfa9d8-149e-4cf7-88b3-6b53bcf09957-294x300.jpg 294w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/01\/7cdfa9d8-149e-4cf7-88b3-6b53bcf09957-768x785.jpg 768w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/01\/7cdfa9d8-149e-4cf7-88b3-6b53bcf09957-640x654.jpg 640w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/01\/7cdfa9d8-149e-4cf7-88b3-6b53bcf09957-720x736.jpg 720w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/01\/7cdfa9d8-149e-4cf7-88b3-6b53bcf09957.jpg 960w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/><\/p>\n<h2>Estat\u00edsticas para o Resultado Lotof\u00e1cil 3315<\/h2>\n<p>. &#8230;  &#8230;. ( Em destaque, as dezenas que vieram nesse Resultado Lotof\u00e1cil 3315 )<br \/>\n<strong>Dezenas que mais sa\u00edram<\/strong>&#8230;.<\/p>\n<p>     20 =>(2084);;; 10 => (2078);;; <strong>25 <\/strong> => (2054);;; <strong>11<\/strong> => (2030);;; 13 => (2016);;; <strong>24<\/strong> => (2014);;; <strong>14 <\/strong>=> (2008);;; <strong>03<\/strong> => (2002);;; <strong>04<\/strong> => (2001);;; 05 => (2000);;; <strong>12<\/strong> => (1997);;; 01 => (1996);;; <strong>09; 18<\/strong> => (1983);;; <strong>02<\/strong> => (1982);;; 22 => (1980).<\/p>\n<p><strong>Dezenas que menos sa\u00edram<\/strong> &#8230;&#8230; <\/p>\n<p>16 => (1895);;; <strong>08 <\/strong>=> (1927);;; 23 => (1936);;; <strong>06<\/strong> => (1939);;; <strong>17<\/strong> => (1948);;; <strong>07<\/strong> => (1951);;; 15  => (1964);;; <strong>21<\/strong> => (1967);;; 19 => (1975).<\/p>\n<hr>\n<p>Dezenas que n\u00e3o sa\u00edram no concurso anterior &#8211; Lotof\u00e1cil 3314:  &#8230;&#8230;    &#8230;. ( Em destaque, as dezenas que vieram nesse Resultado Lotof\u00e1cil 3315 )<\/p>\n<p>                       23 &#8211;   (05 sorteios atrasada)<br \/>\n                       <strong>12<\/strong>  &#8211;  (03 sorteios atrasada)<br \/>\n                       <strong>21<\/strong>  &#8211;  (02 sorteios atrasada)<br \/>\n                       20; <strong>04; 09<\/strong>; 16; <strong>18; 24; 11<\/strong>   &#8211;  (01 sorteio atrasadas)<br \/>\n======<br \/>\n<strong>Presen\u00e7a atual (sorteios seguidos) das Dezenas:<\/strong><\/p>\n<p> <strong>01 sorteio<\/strong>:  10; 22; <strong>02; 03; 08; 25<\/strong>; 15<br \/>\n <strong>02 sorteios<\/strong>: <strong>07<\/strong>; 19; <strong>14<\/strong><br \/>\n <strong>03 sorteios<\/strong>: 01; 13<br \/>\n <strong>04 sorteios<\/strong>: <strong>17<\/strong><br \/>\n <strong>05 sorteios<\/strong>: <strong>06<\/strong><br \/>\n <strong>06 sorteios<\/strong>: 05<\/p>\n<p><strong>No Resultado Lotof\u00e1cil 3315, REPETIRAM 08 DEZENAS DO SORTEIO ANTERIOR ( LF-3314 ).<\/strong><br \/>\n\u2022\u2022\u2022\u2022\u2022\u2022\u2022\u2022<\/p>\n<h3>Palpite Fixo do Midas para o Resultado Lotof\u00e1cil 3315<\/h3>\n<p><strong>02; 03; 04; 07; 08; 11; 13; 14; 17; 18; 19; 20; 22; 23; 24<\/strong><\/p>\n<p>==&gt; <em><strong>10 acertos!!<\/strong><\/em>.<\/p>\n<p><em>&#8220;esse \u00e9 o Palpite Fixo do Site, ainda n\u00e3o deu 14 e 15 pontos, ser\u00e1 mudado assim que isso ocorrer&#8221; &#8230;<\/em><\/p>\n<p><em>MidasSorte, o jogo por esporte!!!<\/em><br \/>\nPublicidade<br \/>\n<ins class=\"adsbygoogle\"\n     style=\"display:block;min-height:100px\"\n     data-ad-client=\"ca-pub-2731125202615360\"\n     data-ad-slot=\"5848493679\"\n     data-ad-format=\"auto\"\n     data-full-width-responsive=\"true\"><\/ins><\/p>\n<p>Apesar de n\u00e3o ser necess\u00e1rio registrar o jogo para participar com o Palpite, sugerimos que voc\u00ea fa\u00e7a seu jogo na Lot\u00e9rica e o coloque aqui como Palpite, inscreva-se para isso.. Aumente suas chances de encontrar a Sorte!&#8230; Boa Sorte e Bom Divertimento! ATEN\u00c7\u00c3O: O SITE N\u00c3O ENVIA PALPITES \u00c0S PESSOAS!<br \/>\nFa\u00e7a sua aposta na Lot\u00e9rica, no aplicativo ou no site da Caixa e confira conosco o Resultado Lotof\u00e1cil 3315.<br \/>\nAl\u00e9m disso, interaja conosco aqui no <a href=\"https:\/\/midassorte.com.br\/resultado\/category\/voce-e-bom-de-palpite-participe-aqui\/\">PALPITES BONIFICADOS<\/a>. Ajude-nos a prestar um servi\u00e7o de informa\u00e7\u00e3o cada vez melhor para voc\u00ea. Deixe sua opini\u00e3o. <\/p>\n<p>Junte os amigos, jogue em grupo, fa\u00e7a Bol\u00f5es. Est\u00e1 provado: o jogo compartilhado faz bem, tornando-nos mais soci\u00e1veis! Obter o pr\u00eamio m\u00e1ximo no concurso Lotof\u00e1cil \u00e9, sem d\u00favida, uma quest\u00e3o de jogar, habilitando-nos \u00e0 Sorte!<\/p>\n<p><strong>Guarde bem o registro do jogo, pois ele \u00e9 o seu comprovante para recebimento de pr\u00eamios.<\/strong><\/p>\n<hr \/>\n<p>Numa condi\u00e7\u00e3o normal, no Resultado Lotof\u00e1cil 3315, \u00e9 esperado que se repitam 8 a 10 dezenas que sa\u00edram e venham 7 a 5 das que n\u00e3o sa\u00edram no concurso anterior. Tamb\u00e9m, h\u00e1 a tend\u00eancia em rela\u00e7\u00e3o aos n\u00fameros Pares\/Impares, respectivamente, apresentam a rela\u00e7\u00e3o 6&#215;9; 7&#215;8; 8&#215;7.<\/p>\n<h2>Informa\u00e7\u00f5es Importantes sobre a Lotof\u00e1cil<\/h2>\n<p>A Lotof\u00e1cil \u00e9 uma modalidade de loteria administrada pela Caixa Econ\u00f4mica Federal. Apenas maiores de 18 anos podem apostar, conforme Art. 81, inciso VI, da lei 8.069\/90. Essa Loteria oficial tem cunho social, com parte da arrecada\u00e7\u00e3o, sob a tutela da Uni\u00e3o, aplicada em v\u00e1rios setores da sociedade (Seguridade; Educa\u00e7\u00e3o; Cultura; Seguran\u00e7a P\u00fablica; Esporte). Vide tabela dessas aplica\u00e7\u00f5es no site da <a href=\"http:\/\/www.caixa.gov.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Caixa Econ\u00f4mica Federal<\/a>.<\/p>\n<p>Na Lotof\u00e1cil, voc\u00ea escolhe 15 n\u00fameros em 25 n\u00fameros e ganha se acertar <strong>15, 14, 13, 12, 11 n\u00fameros<\/strong>. Ela \u00e9 simples de apostar. Voc\u00ea pode apostar uma quantidade maior de n\u00fameros (15 a 20), pagando mais pela aposta e os pr\u00eamios s\u00e3o acrescidos conforme o jogo feito ( vide tabela site da Caixa); pode deixar que o sistema escolha os n\u00fameros (Surpresinha) e\/ou repetir o mesmo jogo por at\u00e9 12 testes (Teimosinha).<\/p>\n<p><strong>Valores a pagar pelas apostas: Tabela da Caixa<\/strong> (a partir de 02\/05\/2023)<br \/>\nPara a aposta simples, de <strong>15 n\u00fameros: R$ 3,00<\/strong>.<br \/>\n\u00c9 poss\u00edvel apostar com mais n\u00fameros:<br \/>\n<strong>16 n\u00fameros: R$ 48,00; 17 n\u00fameros: R$ 408,00; 18 n\u00fameros: R$ 2.448,00; 19 n\u00fameros: R$ 11.628,00; 20 n\u00fameros: R$ 46.512,00<\/strong><\/p>\n<hr \/>\n<h3>Desafio Interativo &#8211; MidasSorte &#8211; Palpites da Lotof\u00e1cil<\/h3>\n<p>Proposta: Ap\u00f3s Identifica\u00e7\u00e3o,  Coloque, em &#8220;Coment\u00e1rios&#8221;<\/strong> <em>um palpite seu de 15 n\u00fameros para o resultado da Lotof\u00e1cil &#8230;<\/em> e , <strong>ap\u00f3s Identifica\u00e7\u00e3o, <\/strong>,as Pessoas que conseguirem mais pontos que nosso palpite ter\u00e3o participa\u00e7\u00e3o na bonifica\u00e7\u00e3o de 3,00 bnM (bonusMidas), que , proporcionalmente, lhes ser\u00e1 creditado na Planilha de Controle de bnMidas &#8211;  MidasSorte de Palpites. Esse valor, a crit\u00e9rio da Pessoa, poder\u00e1 ser utilizado em participa\u00e7\u00f5es em Jogos MidasSorte ou ser feito o resgate em esp\u00e9cie. Al\u00e9m disso, haver\u00e1 participa\u00e7\u00e3o em Jogos Pr\u00eamio e\/ou resgate de bnMidas, no final da Etapa, conforme o Ranking de pontua\u00e7\u00e3o. ATEN\u00c7\u00c3O: O SITE N\u00c3O ENVIA PALPITES \u00c0S PESSOAS!<\/p>\n<p><strong>Como se Identificar:<\/strong><br \/>\n&#8211; Envie um E-mail para: <strong>midasgarante@gmail.com<\/strong> , dizendo que voc\u00ea leu e entendeu as regras e deseja participar de nosso Processo interativo de Palpites e lhe retornaremos solicitando suas informa\u00e7\u00f5es.<\/p>\n<hr \/>\n<p><strong>Aten\u00e7\u00e3o: Em nosso site, <a href=\"http:\/\/midassorte.com.br\/resultado\/\" target=\"_blank\" rel=\"noopener noreferrer\">midassorte.com.br<\/a>, n\u00e3o temos promo\u00e7\u00f5es por telefone\/mensagens e n\u00e3o fazemos quaisquer contatos\/vendas por telefone. <\/p>\n<p><strong>N\u00c3O VENDEMOS JOGOS\/APOSTAS.<\/strong><br \/>\nNosso trabalho consiste em divulga\u00e7\u00e3o de resultados e palpites de Loterias, atrav\u00e9s do Site.<\/p>\n<hr \/>\n<p>Nossos \u00daNICOS canais de comunica\u00e7\u00e3o s\u00e3o:<br \/>\n\u2022\u2022\u2022 <strong>E-MAIL<\/strong>: midasgarante@gmail.com<br \/>\n\u2022\u2022\u2022 <strong>WHATSAPP<\/strong>: MidasSorte: (31) 97524-8524<\/strong><\/p>\n<hr \/>\n<h3>BOA SORTE nesse Resultado Lotof\u00e1cil 3315!  <\/h3>\n<p>Editor Respons\u00e1vel: <em>Jos\u00e9 Raimundo Vieira<\/em>.<\/p>\n<hr \/>\n<p><span class=\"lm\">Link para voc\u00ea comprar a sua Tele Sena <\/span>:<br \/>\n<a href=\"https:\/\/www.telesena.com.br\/campanhas\/927\/crm\/sms.html?af=A90D9B20-A95A-4BA8-8ED7-F9EA5482D809 \/\" class=\"ds\" span target=\"_blank\" rel=\"noopener\">LINK SEGURO para o SITE OFICIAL DA TELE SENA&#8230;clique aqui.<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/02\/93f30877-7ecb-4bdd-9d8e-0782927c0878-300x188.jpg\" alt=\"TELE SENA de CARNAVAL 2025\" width=\"300\" height=\"188\" class=\"alignnone size-medium wp-image-370235\" srcset=\"https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/02\/93f30877-7ecb-4bdd-9d8e-0782927c0878-300x188.jpg 300w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/02\/93f30877-7ecb-4bdd-9d8e-0782927c0878-1024x642.jpg 1024w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/02\/93f30877-7ecb-4bdd-9d8e-0782927c0878-768x481.jpg 768w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/02\/93f30877-7ecb-4bdd-9d8e-0782927c0878-640x401.jpg 640w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/02\/93f30877-7ecb-4bdd-9d8e-0782927c0878-720x451.jpg 720w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/02\/93f30877-7ecb-4bdd-9d8e-0782927c0878-325x205.jpg 325w, https:\/\/midassorte.com.br\/resultado\/wp-content\/uploads\/2025\/02\/93f30877-7ecb-4bdd-9d8e-0782927c0878.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>\u2022\u2022\u2022 ESTAMOS AQUI!..h\u00e1 11 anos&#8230; &#8220;Dia a dia&#8230;.Loteria a loteria&#8230;Resultados e Palpites de Loterias!!! N\u00c3O VENDEMOS JOGOS\/APOSTAS &#8211; ATEN\u00c7\u00c3O: MIDASSORTE => N\u00c3O SOMOS, N\u00c3O TEMOS PLATAFORMA DE APOSTAS!!!&#8230; (cuidado com imita\u00e7\u00f5es) \u2022\u2022\u2022 Confira o resultado da Lotof\u00e1cil 3315, hoje, nesse &hellip; <a href=\"https:\/\/midassorte.com.br\/resultado\/resultado-lotofacil-3315-sabado-08-02-informacao\/\">Continuar lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[],"class_list":["post-370785","post","type-post","status-publish","format-standard","hentry","category-lotofacil-3"],"_links":{"self":[{"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/posts\/370785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/comments?post=370785"}],"version-history":[{"count":0,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/posts\/370785\/revisions"}],"wp:attachment":[{"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/media?parent=370785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/categories?post=370785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/midassorte.com.br\/resultado\/wp-json\/wp\/v2\/tags?post=370785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}